{"id":2931,"date":"2025-04-17T13:30:05","date_gmt":"2025-04-17T13:30:05","guid":{"rendered":"https:\/\/www.hummelitalia.com\/?post_type=prodotto-catalogo&#038;p=2931"},"modified":"2025-04-17T13:33:38","modified_gmt":"2025-04-17T13:33:38","slug":"hsk-inox-hd","status":"publish","type":"prodotto-catalogo","link":"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/","title":{"rendered":"HSK-INOX-HD"},"content":{"rendered":"","protected":false},"featured_media":2933,"template":"","meta":{"_acf_changed":false},"categoria":[43],"icona-certificazione":[38,58,57],"class_list":["post-2931","prodotto-catalogo","type-prodotto-catalogo","status-publish","has-post-thumbnail","hentry","categoria-pressacavi-per-applicazioni-speciali","icona-certificazione-ce","icona-certificazione-ecolab","icona-certificazione-emv-emc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HSK-INOX-HD - Hummel Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HSK-INOX-HD - Hummel Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/\" \/>\n<meta property=\"og:site_name\" content=\"Hummel Italia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-17T13:33:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/04\/l_hsk-inox-hd_5fd51a19a1208ec405f20be3cd47d70a.png\" \/>\n\t<meta property=\"og:image:width\" content=\"403\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/prodotto-catalogo\\\/hsk-inox-hd\\\/\",\"url\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/prodotto-catalogo\\\/hsk-inox-hd\\\/\",\"name\":\"HSK-INOX-HD - Hummel Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/prodotto-catalogo\\\/hsk-inox-hd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/prodotto-catalogo\\\/hsk-inox-hd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hummelitalia.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/l_hsk-inox-hd_5fd51a19a1208ec405f20be3cd47d70a.png\",\"datePublished\":\"2025-04-17T13:30:05+00:00\",\"dateModified\":\"2025-04-17T13:33:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/prodotto-catalogo\\\/hsk-inox-hd\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/prodotto-catalogo\\\/hsk-inox-hd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/prodotto-catalogo\\\/hsk-inox-hd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hummelitalia.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/l_hsk-inox-hd_5fd51a19a1208ec405f20be3cd47d70a.png\",\"contentUrl\":\"https:\\\/\\\/www.hummelitalia.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/l_hsk-inox-hd_5fd51a19a1208ec405f20be3cd47d70a.png\",\"width\":403,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/prodotto-catalogo\\\/hsk-inox-hd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cable glands for special applications\",\"item\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/categoria\\\/cable-glands-for-special-applications\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HSK-INOX-HD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/\",\"name\":\"Hummel Italia\",\"description\":\"My WordPress Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#organization\",\"name\":\"Hummel Italia\",\"url\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hummelitalia.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/hummel-logo-270.png\",\"contentUrl\":\"https:\\\/\\\/www.hummelitalia.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/hummel-logo-270.png\",\"width\":270,\"height\":135,\"caption\":\"Hummel Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HSK-INOX-HD - Hummel Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/","og_locale":"en_US","og_type":"article","og_title":"HSK-INOX-HD - Hummel Italia","og_url":"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/","og_site_name":"Hummel Italia","article_modified_time":"2025-04-17T13:33:38+00:00","og_image":[{"width":403,"height":608,"url":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/04\/l_hsk-inox-hd_5fd51a19a1208ec405f20be3cd47d70a.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/","url":"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/","name":"HSK-INOX-HD - Hummel Italia","isPartOf":{"@id":"https:\/\/www.hummelitalia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/#primaryimage"},"image":{"@id":"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/04\/l_hsk-inox-hd_5fd51a19a1208ec405f20be3cd47d70a.png","datePublished":"2025-04-17T13:30:05+00:00","dateModified":"2025-04-17T13:33:38+00:00","breadcrumb":{"@id":"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/#primaryimage","url":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/04\/l_hsk-inox-hd_5fd51a19a1208ec405f20be3cd47d70a.png","contentUrl":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/04\/l_hsk-inox-hd_5fd51a19a1208ec405f20be3cd47d70a.png","width":403,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/www.hummelitalia.com\/en\/prodotto-catalogo\/hsk-inox-hd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hummelitalia.com\/en\/"},{"@type":"ListItem","position":2,"name":"Cable glands for special applications","item":"https:\/\/www.hummelitalia.com\/en\/categoria\/cable-glands-for-special-applications\/"},{"@type":"ListItem","position":3,"name":"HSK-INOX-HD"}]},{"@type":"WebSite","@id":"https:\/\/www.hummelitalia.com\/en\/#website","url":"https:\/\/www.hummelitalia.com\/en\/","name":"Hummel Italia","description":"My WordPress Blog","publisher":{"@id":"https:\/\/www.hummelitalia.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hummelitalia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.hummelitalia.com\/en\/#organization","name":"Hummel Italia","url":"https:\/\/www.hummelitalia.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hummelitalia.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/01\/hummel-logo-270.png","contentUrl":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/01\/hummel-logo-270.png","width":270,"height":135,"caption":"Hummel Italia"},"image":{"@id":"https:\/\/www.hummelitalia.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/prodotto-catalogo\/2931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/prodotto-catalogo"}],"about":[{"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/types\/prodotto-catalogo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/media\/2933"}],"wp:attachment":[{"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/media?parent=2931"}],"wp:term":[{"taxonomy":"categoria","embeddable":true,"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/categoria?post=2931"},{"taxonomy":"icona-certificazione","embeddable":true,"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/icona-certificazione?post=2931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}