{"id":5146,"date":"2025-03-07T15:35:32","date_gmt":"2025-03-07T15:35:32","guid":{"rendered":"https:\/\/www.hummelitalia.com\/products\/cable-glands\/"},"modified":"2025-06-05T15:45:55","modified_gmt":"2025-06-05T15:45:55","slug":"cable-glands","status":"publish","type":"page","link":"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/","title":{"rendered":"Cable glands"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5146\" class=\"elementor elementor-5146 elementor-1088\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-353d6a0 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"353d6a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc1caa1 elementor-widget elementor-widget-heading\" data-id=\"dc1caa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cable glands and cable protection systems<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a60cbc elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"4a60cbc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1bffebc e-con-full e-flex e-con e-child\" data-id=\"1bffebc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6e9dfe3 e-con-full e-flex e-con e-child\" data-id=\"6e9dfe3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-952c4be e-con-full e-flex e-con e-child\" data-id=\"952c4be\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d8dac84 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d8dac84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png\" class=\"attachment-full size-full wp-image-891\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">Plastic cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f981fb6 e-con-full e-flex e-con e-child\" data-id=\"f981fb6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6ae2dc elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c6ae2dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-metallo\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo.png\" class=\"attachment-full size-full wp-image-890\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-metallo\/\">Metal cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31415d0 e-con-full e-flex e-con e-child\" data-id=\"31415d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a2416d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2a2416d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC.png\" class=\"attachment-full size-full wp-image-888\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc\/\">EMC cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bb65c0 e-con-full e-flex e-con e-child\" data-id=\"1bb65c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d4d323 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2d4d323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-per-applicazioni-speciali\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali.png\" class=\"attachment-full size-full wp-image-892\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-per-applicazioni-speciali\/\">Cable glands for special applications<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36179ca e-con-full e-flex e-con e-child\" data-id=\"36179ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1539b27 e-con-full e-flex e-con e-child\" data-id=\"1539b27\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c43721 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2c43721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-din\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_DIN-2.png\" class=\"attachment-full size-full wp-image-1129\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_DIN-2.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_DIN-2-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-din\/\">DIN cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d4960e e-con-full e-flex e-con e-child\" data-id=\"4d4960e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f05de72 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"f05de72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/accessori\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_accessori.png\" class=\"attachment-full size-full wp-image-885\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_accessori.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_accessori-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/accessori\/\">Accessories<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cd403c e-con-full e-flex e-con e-child\" data-id=\"5cd403c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f2d818 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6f2d818\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-ex\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_Ex-2.png\" class=\"attachment-full size-full wp-image-1133\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_Ex-2.png 380w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_Ex-2-300x189.png 300w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-ex\/\">Ex cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-46daaae e-con-full e-flex e-con e-child\" data-id=\"46daaae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e2cc96 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9e2cc96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc-ex-e\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-Ex.png\" class=\"attachment-full size-full wp-image-920\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-Ex.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-Ex-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc-ex-e\/\">EMC-Ex e cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67e23ce e-con-full e-flex e-con e-child\" data-id=\"67e23ce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-99be892 e-con-full e-flex e-con e-child\" data-id=\"99be892\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e7c1dc elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1e7c1dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/exios-pressacavi-per-hazardous-areas\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_EXIOS_pressacavi_per_hazardous_areas.png\" class=\"attachment-full size-full wp-image-886\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_EXIOS_pressacavi_per_hazardous_areas.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_EXIOS_pressacavi_per_hazardous_areas-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/exios-pressacavi-per-hazardous-areas\/\">EXIOS cable glands for \"Hazordous Areas\"<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-86487c0 e-con-full e-flex e-con e-child\" data-id=\"86487c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf6c204 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bf6c204\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/sistemi-di-protezione-dei-cavi\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"432\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_sistemi_di_protezione_dei_cavi.png\" class=\"attachment-full size-full wp-image-930\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_sistemi_di_protezione_dei_cavi.png 432w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_sistemi_di_protezione_dei_cavi-300x167.png 300w\" sizes=\"(max-width: 432px) 100vw, 432px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/sistemi-di-protezione-dei-cavi\/\">Cable protection systems<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1790de5 e-con-full e-flex e-con e-child\" data-id=\"1790de5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-95968ef e-con-full e-flex e-con e-child\" data-id=\"95968ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a70f38 e-flex e-con-boxed e-con e-parent\" data-id=\"6a70f38\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0d2805 elementor-widget elementor-widget-heading\" data-id=\"b0d2805\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Cable glands<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b73098 elementor-widget elementor-widget-breadcrumbs\" data-id=\"1b73098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.hummelitalia.com\/en\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5074ba0 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"5074ba0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e78f164 e-con-full e-flex e-con e-child\" data-id=\"e78f164\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e1084ca e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"e1084ca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d74d46d elementor-widget elementor-widget-heading\" data-id=\"d74d46d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cable glands and cable protection systems<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-535475b e-con-full e-flex e-con e-child\" data-id=\"535475b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f701c2e e-con-full e-flex e-con e-child\" data-id=\"f701c2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e085268 e-con-full e-flex e-con e-child\" data-id=\"e085268\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26011e6 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"26011e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png\" class=\"attachment-full size-full wp-image-891\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">Plastic cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-186a9bc e-con-full e-flex e-con e-child\" data-id=\"186a9bc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-324993f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"324993f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-metallo\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo.png\" class=\"attachment-full size-full wp-image-890\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-metallo\/\">Metal cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cded621 e-con-full e-flex e-con e-child\" data-id=\"cded621\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d29dc33 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d29dc33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC.png\" class=\"attachment-full size-full wp-image-888\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc\/\">EMC cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c867dcb e-con-full e-flex e-con e-child\" data-id=\"c867dcb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd07855 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cd07855\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-per-applicazioni-speciali\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali.png\" class=\"attachment-full size-full wp-image-892\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-per-applicazioni-speciali\/\">Cable glands for special applications<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-815668d e-con-full e-flex e-con e-child\" data-id=\"815668d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7230e3a e-con-full e-flex e-con e-child\" data-id=\"7230e3a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c9cfd7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"4c9cfd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-din\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_DIN.png\" class=\"attachment-full size-full wp-image-887\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_DIN.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_DIN-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-din\/\">DIN cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8eca9d9 e-con-full e-flex e-con e-child\" data-id=\"8eca9d9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbd9bbd elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bbd9bbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/accessori\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_accessori.png\" class=\"attachment-full size-full wp-image-885\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_accessori.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_accessori-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/accessori\/\">Accessories<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42dfecf e-con-full e-flex e-con e-child\" data-id=\"42dfecf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c0ba46 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3c0ba46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-ex\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_Ex-2.png\" class=\"attachment-full size-full wp-image-1133\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_Ex-2.png 380w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_Ex-2-300x189.png 300w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-ex\/\">Ex cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ae84d2 e-con-full e-flex e-con e-child\" data-id=\"5ae84d2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90d3857 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"90d3857\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc-ex-e\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-Ex.png\" class=\"attachment-full size-full wp-image-920\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-Ex.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-Ex-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc-ex-e\/\">EMC-Ex e cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ba468c e-con-full e-flex e-con e-child\" data-id=\"3ba468c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3bfa379 e-con-full e-flex e-con e-child\" data-id=\"3bfa379\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80aae30 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"80aae30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/accessori-ex\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"85\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/04\/csm_l_ex-accessories_599e9cf1e0c294233fd0792bdf67a393_a18db23af4.png\" class=\"attachment-full size-full wp-image-2942\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/accessori-ex\/\">Ex accessories<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ce441c e-con-full e-flex e-con e-child\" data-id=\"5ce441c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f3363f elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1f3363f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/exios-pressacavi-per-hazardous-areas\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_EXIOS_pressacavi_per_hazardous_areas.png\" class=\"attachment-full size-full wp-image-886\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_EXIOS_pressacavi_per_hazardous_areas.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_EXIOS_pressacavi_per_hazardous_areas-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/exios-pressacavi-per-hazardous-areas\/\">EXIOS cable glands for \"Hazordous Areas\"<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f72992f e-con-full e-flex e-con e-child\" data-id=\"f72992f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7221105 e-con-full e-flex e-con e-child\" data-id=\"7221105\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75c9ad6 elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"75c9ad6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0cafe6a e-con-full e-flex e-con e-child\" data-id=\"0cafe6a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-908a17d e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"908a17d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff91d00 elementor-widget elementor-widget-heading\" data-id=\"ff91d00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cable glands and cable protection systems<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e6959f e-con-full e-flex e-con e-child\" data-id=\"6e6959f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-041dd52 e-con-full e-flex e-con e-child\" data-id=\"041dd52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4cd49e4 e-con-full e-flex e-con e-child\" data-id=\"4cd49e4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce308b0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ce308b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png\" class=\"attachment-full size-full wp-image-891\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">Plastic cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd33069 e-con-full e-flex e-con e-child\" data-id=\"cd33069\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2145124 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2145124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-metallo\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo.png\" class=\"attachment-full size-full wp-image-890\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-metallo\/\">Metal cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c91ab64 e-con-full e-flex e-con e-child\" data-id=\"c91ab64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-992908e e-con-full e-flex e-con e-child\" data-id=\"992908e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4aa31e3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"4aa31e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC.png\" class=\"attachment-full size-full wp-image-888\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc\/\">EMC cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92488c8 e-con-full e-flex e-con e-child\" data-id=\"92488c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0aa6ada elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0aa6ada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-per-applicazioni-speciali\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali.png\" class=\"attachment-full size-full wp-image-892\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-per-applicazioni-speciali\/\">Cable glands and cable protection systems<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92c1a9a e-con-full e-flex e-con e-child\" data-id=\"92c1a9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ff00717 e-con-full e-flex e-con e-child\" data-id=\"ff00717\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51c8b9e elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"51c8b9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-din\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_DIN.png\" class=\"attachment-full size-full wp-image-887\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_DIN.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_DIN-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-din\/\">DIN cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1aaa4a0 e-con-full e-flex e-con e-child\" data-id=\"1aaa4a0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7dc43a8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"7dc43a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/accessori\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_accessori.png\" class=\"attachment-full size-full wp-image-885\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_accessori.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_accessori-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/accessori\/\">Accessories<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-920723c e-con-full e-flex e-con e-child\" data-id=\"920723c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8c49376 e-con-full e-flex e-con e-child\" data-id=\"8c49376\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc567e7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"dc567e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-ex\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_Ex-2.png\" class=\"attachment-full size-full wp-image-1133\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_Ex-2.png 380w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_Ex-2-300x189.png 300w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-ex\/\">EX cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e019a2a e-con-full e-flex e-con e-child\" data-id=\"e019a2a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fbd4ed7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"fbd4ed7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc-ex-e\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-Ex.png\" class=\"attachment-full size-full wp-image-920\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-Ex.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-Ex-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-emc-ex-e\/\">EMC-Ex e cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d278dd e-con-full e-flex e-con e-child\" data-id=\"7d278dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5fadf49 e-con-full e-flex e-con e-child\" data-id=\"5fadf49\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92f0262 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"92f0262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/accessori-ex\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"85\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/04\/csm_l_ex-accessories_599e9cf1e0c294233fd0792bdf67a393_a18db23af4.png\" class=\"attachment-full size-full wp-image-2942\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/accessori-ex\/\">Ex accessories<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ec19e2 e-con-full e-flex e-con e-child\" data-id=\"6ec19e2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-624f550 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"624f550\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/exios-pressacavi-per-hazardous-areas\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_EXIOS_pressacavi_per_hazardous_areas.png\" class=\"attachment-full size-full wp-image-886\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_EXIOS_pressacavi_per_hazardous_areas.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_EXIOS_pressacavi_per_hazardous_areas-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/exios-pressacavi-per-hazardous-areas\/\">EXIOS cable glands for \"Hazordous Areas\"<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9617a40 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"9617a40\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-51351d9 e-con-full e-flex e-con e-child\" data-id=\"51351d9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ce6ac61 e-con-full e-flex e-con e-child\" data-id=\"ce6ac61\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f6ae7ed elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f6ae7ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-lightbulb\" viewBox=\"0 0 352 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 80c-52.94 0-96 43.06-96 96 0 8.84 7.16 16 16 16s16-7.16 16-16c0-35.3 28.72-64 64-64 8.84 0 16-7.16 16-16s-7.16-16-16-16zM96.06 459.17c0 3.15.93 6.22 2.68 8.84l24.51 36.84c2.97 4.46 7.97 7.14 13.32 7.14h78.85c5.36 0 10.36-2.68 13.32-7.14l24.51-36.84c1.74-2.62 2.67-5.7 2.68-8.84l.05-43.18H96.02l.04 43.18zM176 0C73.72 0 0 82.97 0 176c0 44.37 16.45 84.85 43.56 115.78 16.64 18.99 42.74 58.8 52.42 92.16v.06h48v-.12c-.01-4.77-.72-9.51-2.15-14.07-5.59-17.81-22.82-64.77-62.17-109.67-20.54-23.43-31.52-53.15-31.61-84.14-.2-73.64 59.67-128 127.95-128 70.58 0 128 57.42 128 128 0 30.97-11.24 60.85-31.65 84.14-39.11 44.61-56.42 91.47-62.1 109.46a47.507 47.507 0 0 0-2.22 14.3v.1h48v-.05c9.68-33.37 35.78-73.18 52.42-92.16C335.55 260.85 352 220.37 352 176 352 78.8 273.2 0 176 0z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28affa2 elementor-widget elementor-widget-heading\" data-id=\"28affa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cable glands and cable protection systems<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81b2deb e-con-full e-flex e-con e-child\" data-id=\"81b2deb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8abecc4 e-con-full e-flex e-con e-child\" data-id=\"8abecc4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-69cc10c e-con-full e-flex e-con e-child\" data-id=\"69cc10c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4149ca elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b4149ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png\" class=\"attachment-full size-full wp-image-891\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">Plastic cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e3e2da e-con-full e-flex e-con e-child\" data-id=\"0e3e2da\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1c890d elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"d1c890d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo.png\" class=\"attachment-full size-full wp-image-890\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_metallo-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">Metal cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8da49ca e-con-full e-flex e-con e-child\" data-id=\"8da49ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0fe15aa e-con-full e-flex e-con e-child\" data-id=\"0fe15aa\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8499920 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8499920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC.png\" class=\"attachment-full size-full wp-image-888\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_EMC-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">EMC cable glands<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f191f6 e-con-full e-flex e-con e-child\" data-id=\"3f191f6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fadb9e8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"fadb9e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"240\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali.png\" class=\"attachment-full size-full wp-image-892\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali.png 424w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_per_applicazioni_speciali-300x170.png 300w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">Cable glands for special applications<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ad901f e-con-full e-flex e-con e-child\" data-id=\"3ad901f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ea2af7 elementor-widget elementor-widget-button\" data-id=\"7ea2af7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Find out all<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2d603c e-con-full e-flex e-con e-child\" data-id=\"a2d603c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-590e750 e-con-full e-flex e-con e-child\" data-id=\"590e750\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eab1722 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"eab1722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-lightbulb\" viewBox=\"0 0 352 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 80c-52.94 0-96 43.06-96 96 0 8.84 7.16 16 16 16s16-7.16 16-16c0-35.3 28.72-64 64-64 8.84 0 16-7.16 16-16s-7.16-16-16-16zM96.06 459.17c0 3.15.93 6.22 2.68 8.84l24.51 36.84c2.97 4.46 7.97 7.14 13.32 7.14h78.85c5.36 0 10.36-2.68 13.32-7.14l24.51-36.84c1.74-2.62 2.67-5.7 2.68-8.84l.05-43.18H96.02l.04 43.18zM176 0C73.72 0 0 82.97 0 176c0 44.37 16.45 84.85 43.56 115.78 16.64 18.99 42.74 58.8 52.42 92.16v.06h48v-.12c-.01-4.77-.72-9.51-2.15-14.07-5.59-17.81-22.82-64.77-62.17-109.67-20.54-23.43-31.52-53.15-31.61-84.14-.2-73.64 59.67-128 127.95-128 70.58 0 128 57.42 128 128 0 30.97-11.24 60.85-31.65 84.14-39.11 44.61-56.42 91.47-62.1 109.46a47.507 47.507 0 0 0-2.22 14.3v.1h48v-.05c9.68-33.37 35.78-73.18 52.42-92.16C335.55 260.85 352 220.37 352 176 352 78.8 273.2 0 176 0z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08148d7 elementor-widget elementor-widget-heading\" data-id=\"08148d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Circular connectors<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd39345 e-con-full e-flex e-con e-child\" data-id=\"cd39345\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;arrow&quot;}\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 700 10\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M350,10L340,0h20L350,10z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f95779 e-con-full e-flex e-con e-child\" data-id=\"0f95779\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-22c3fdc e-con-full e-flex e-con e-child\" data-id=\"22c3fdc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e390ed9 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"e390ed9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"434\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M12_Power.png\" class=\"attachment-full size-full wp-image-938\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M12_Power.png 780w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M12_Power-600x334.png 600w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M12_Power-300x167.png 300w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M12_Power-768x427.png 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">M12 Power<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e533b04 e-con-full e-flex e-con e-child\" data-id=\"e533b04\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1eab363 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1eab363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"434\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M16.png\" class=\"attachment-full size-full wp-image-945\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M16.png 780w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M16-600x334.png 600w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M16-300x167.png 300w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M16-768x427.png 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">Circular connectors M16<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-256a19b e-con-full e-flex e-con e-child\" data-id=\"256a19b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-557ee2d e-con-full e-flex e-con e-child\" data-id=\"557ee2d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d48327 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"4d48327\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"434\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M27-1.png\" class=\"attachment-full size-full wp-image-968\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M27-1.png 780w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M27-1-600x334.png 600w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M27-1-300x167.png 300w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_M27-1-768x427.png 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">Circular connectors M27<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-490910a e-con-full e-flex e-con e-child\" data-id=\"490910a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bda9857 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bda9857\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\" tabindex=\"-1\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"434\" src=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_INOX-1.png\" class=\"attachment-full size-full wp-image-969\" alt=\"\" srcset=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_INOX-1.png 780w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_INOX-1-600x334.png 600w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_INOX-1-300x167.png 300w, https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_INOX-1-768x427.png 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"https:\/\/www.hummelitalia.com\/en\/categoria\/pressacavi-in-plastica\/\">INOX connectors<\/a><\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68889d3 e-con-full e-flex e-con e-child\" data-id=\"68889d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2e7462 elementor-widget elementor-widget-button\" data-id=\"c2e7462\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.hummelitalia.com\/en\/products\/circular-connectors\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Find out all<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cable glands and cable protection systems Plastic cable glands Metal cable glands EMC cable glands Cable glands for special applications DIN cable glands Accessories Ex cable glands EMC-Ex e cable glands EXIOS cable glands for &#8220;Hazordous Areas&#8221; Cable protection systems Cable glands and cable protection systems Plastic cable glands Metal cable glands EMC cable glands [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":5143,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5146","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cable glands - Hummel Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cable glands - Hummel Italia\" \/>\n<meta property=\"og:description\" content=\"Cable glands and cable protection systems Plastic cable glands Metal cable glands EMC cable glands Cable glands for special applications DIN cable glands Accessories Ex cable glands EMC-Ex e cable glands EXIOS cable glands for &#8220;Hazordous Areas&#8221; Cable protection systems Cable glands and cable protection systems Plastic cable glands Metal cable glands EMC cable glands [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/\" \/>\n<meta property=\"og:site_name\" content=\"Hummel Italia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T15:45:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"424\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/products\\\/cable-glands\\\/\",\"url\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/products\\\/cable-glands\\\/\",\"name\":\"Cable glands - Hummel Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/products\\\/cable-glands\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/products\\\/cable-glands\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hummelitalia.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/home_pressacavi_in_plastica.png\",\"datePublished\":\"2025-03-07T15:35:32+00:00\",\"dateModified\":\"2025-06-05T15:45:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/products\\\/cable-glands\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/products\\\/cable-glands\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/products\\\/cable-glands\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hummelitalia.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/home_pressacavi_in_plastica.png\",\"contentUrl\":\"https:\\\/\\\/www.hummelitalia.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/home_pressacavi_in_plastica.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/products\\\/cable-glands\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cable glands\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/\",\"name\":\"Hummel Italia\",\"description\":\"My WordPress Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#organization\",\"name\":\"Hummel Italia\",\"url\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hummelitalia.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/hummel-logo-270.png\",\"contentUrl\":\"https:\\\/\\\/www.hummelitalia.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/hummel-logo-270.png\",\"width\":270,\"height\":135,\"caption\":\"Hummel Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hummelitalia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cable glands - Hummel Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/","og_locale":"en_US","og_type":"article","og_title":"Cable glands - Hummel Italia","og_description":"Cable glands and cable protection systems Plastic cable glands Metal cable glands EMC cable glands Cable glands for special applications DIN cable glands Accessories Ex cable glands EMC-Ex e cable glands EXIOS cable glands for &#8220;Hazordous Areas&#8221; Cable protection systems Cable glands and cable protection systems Plastic cable glands Metal cable glands EMC cable glands [&hellip;]","og_url":"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/","og_site_name":"Hummel Italia","article_modified_time":"2025-06-05T15:45:55+00:00","og_image":[{"width":424,"height":240,"url":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/","url":"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/","name":"Cable glands - Hummel Italia","isPartOf":{"@id":"https:\/\/www.hummelitalia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/#primaryimage"},"image":{"@id":"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png","datePublished":"2025-03-07T15:35:32+00:00","dateModified":"2025-06-05T15:45:55+00:00","breadcrumb":{"@id":"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/#primaryimage","url":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png","contentUrl":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/03\/home_pressacavi_in_plastica.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hummelitalia.com\/en\/products\/cable-glands\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hummelitalia.com\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.hummelitalia.com\/en\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Cable glands"}]},{"@type":"WebSite","@id":"https:\/\/www.hummelitalia.com\/en\/#website","url":"https:\/\/www.hummelitalia.com\/en\/","name":"Hummel Italia","description":"My WordPress Blog","publisher":{"@id":"https:\/\/www.hummelitalia.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hummelitalia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.hummelitalia.com\/en\/#organization","name":"Hummel Italia","url":"https:\/\/www.hummelitalia.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hummelitalia.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/01\/hummel-logo-270.png","contentUrl":"https:\/\/www.hummelitalia.com\/wp-content\/uploads\/2025\/01\/hummel-logo-270.png","width":270,"height":135,"caption":"Hummel Italia"},"image":{"@id":"https:\/\/www.hummelitalia.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/pages\/5146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/comments?post=5146"}],"version-history":[{"count":1,"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/pages\/5146\/revisions"}],"predecessor-version":[{"id":5147,"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/pages\/5146\/revisions\/5147"}],"up":[{"embeddable":true,"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/pages\/5143"}],"wp:attachment":[{"href":"https:\/\/www.hummelitalia.com\/en\/wp-json\/wp\/v2\/media?parent=5146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}